{"id":635,"count":1,"description":"","link":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/","name":"Artikel ilmiah populer","slug":"artikel-ilmiah-populer","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Artikel ilmiah populer Archives - Ebizmark Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artikel ilmiah populer Archives - Ebizmark Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/\" \/>\n<meta property=\"og:site_name\" content=\"Ebizmark Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artikel ilmiah populer Archives - Ebizmark Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/","og_locale":"en_US","og_type":"article","og_title":"Artikel ilmiah populer Archives - Ebizmark Blog","og_url":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/","og_site_name":"Ebizmark Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/","url":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/","name":"Artikel ilmiah populer Archives - Ebizmark Blog","isPartOf":{"@id":"https:\/\/ebizmark.id\/artikel\/#website"},"breadcrumb":{"@id":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ebizmark.id\/artikel\/tag\/artikel-ilmiah-populer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ebizmark.id\/artikel\/"},{"@type":"ListItem","position":2,"name":"Artikel ilmiah populer"}]},{"@type":"WebSite","@id":"https:\/\/ebizmark.id\/artikel\/#website","url":"https:\/\/ebizmark.id\/artikel\/","name":"Ebizmark Blog","description":"Kumpulan informasi mengenai penelitian, olah data, dosen, mahasiswa","publisher":{"@id":"https:\/\/ebizmark.id\/artikel\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ebizmark.id\/artikel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ebizmark.id\/artikel\/#organization","name":"Ebizmark","alternateName":"PT Ebiz Prima Nusa","url":"https:\/\/ebizmark.id\/artikel\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ebizmark.id\/artikel\/#\/schema\/logo\/image\/","url":"https:\/\/ebizmark.id\/artikel\/wp-content\/uploads\/2022\/11\/cropped-cropped-Logo-Baru-Ebizmark-e1749526996722.png","contentUrl":"https:\/\/ebizmark.id\/artikel\/wp-content\/uploads\/2022\/11\/cropped-cropped-Logo-Baru-Ebizmark-e1749526996722.png","width":200,"height":67,"caption":"Ebizmark"},"image":{"@id":"https:\/\/ebizmark.id\/artikel\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ebizmark.id\/artikel\/wp-json\/wp\/v2\/tags\/635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ebizmark.id\/artikel\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ebizmark.id\/artikel\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ebizmark.id\/artikel\/wp-json\/wp\/v2\/posts?tags=635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}